{"id":5740,"date":"2020-07-04T18:02:43","date_gmt":"2020-07-04T16:02:43","guid":{"rendered":"https:\/\/giessen.dakd.de\/?p=5740"},"modified":"2020-07-29T18:09:14","modified_gmt":"2020-07-29T16:09:14","slug":"wzs-04-07-2020","status":"publish","type":"post","link":"https:\/\/mainz.dakd.de\/am\/wzs-04-07-2020\/","title":{"rendered":"Wort zum Sonntag am 04.07.2020"},"content":{"rendered":"<p><img decoding=\"async\" class=\"size-fusion-600 wp-image-5603 alignnone\" src=\"http:\/\/giessen.dakd.de\/wp-content\/uploads\/2020\/07\/WortZumSonntag-600x400.jpg\" alt=\"\" width=\"600\" height=\"400\" \/><\/p>\n<p><strong>Heute erinnert unsere Kirche an die Auffindung der Schatulle der Muttergottes, in der der \u00dcberlieferung nach die Hl.<\/strong><br \/>\nMuttergottes ihren Kopftuch aufbewahrte. Die Schatulle wurde von zwei griechischen F\u00fcrsten gefunden und von Jerusalem nach Konstantinopel gebracht und in der Hl. Gottesmutter Kirche aufbewahrt.<\/p>\n<p>Im heutigen Sonntagsevangelium erz\u00e4hlt unser Herr das Gleichnis vom Unkraut. \u201eMit dem Himmelreich ist es wie mit einem Mann,<br \/>\nder guten Samen auf seinen Acker s\u00e4te. W\u00e4hrend nun die Menschen schliefen, kam sein Feind, s\u00e4te Unkraut unter den Weizen und ging weg. Als die Saat aufging und sich die \u00c4hren bildeten, kam auch das Unkraut zum Vorschein. Da gingen die Knechte zu dem Gutsherrn und sagten: Herr, hast du nicht guten Samen auf deinen Acker ges\u00e4t? Woher kommt dann das Unkraut? Er antwortete: Das hat ein Feind getan. Da sagten die Knechte zu ihm: Sollen wir gehen und es ausrei\u00dfen? Er entgegnete: Nein, damit ihr nicht zusammen mit dem Unkraut den Weizen ausrei\u00dft. Lasst beides wachsen bis zur Ernte und zur Zeit der Ernte werde ich den Schnittern sagen: Sammelt zuerst das Unkraut und bindet es in B\u00fcndel, um es zu verbrennen; den Weizen aber bringt in meine Scheune!\u201c Mat:13. 34-30.<\/p>\n<p>Auf Wunsch seiner J\u00fcnger erkl\u00e4rt der Herr das Gleichnis wie folgt: Der den guten Samen s\u00e4t, ist der Menschensohn; der Acker ist die Welt; der gute Samen, das sind die Kinder des<br \/>\nReiches; das Unkraut sind die Kinder des B\u00f6sen; der Feind, der es ges\u00e4t hat, ist der Teufel; die Ernte ist das Ende der Welt; die<br \/>\nSchnitter sind die Engel Mat:13.37-39.<\/p>\n<p>Liebe Gl\u00e4ubige, Gott hat diese Welt und den Menschen zum Guten geschaffen. Daher stellt sich die Frage, woher so viel B\u00f6ses und Leid in unser Leben kommt.<br \/>\nDas Gleichnis vom Unkraut hilft uns besser zu verstehen, wie das B\u00f6se durch den Teufel in der von Gott geschaffenen Welt<br \/>\ngeboren wird und wie es funktioniert.<\/p>\n<p>Erstens: Der Feind kommt nachts, im Dunkeln und Geheimen. Der Teufel, handelt nicht offen gegen uns, sondern nutzt oft unseren verwirrten und unsicheren Zustand aus.<br \/>\nZweitens: Der Feind s\u00e4t das Unkraut, als die Kultivierenden des Feldes schlafen. Auch wir sind anf\u00e4lliger f\u00fcr das B\u00f6se,<br \/>\nbesonders wenn wir im spirituellen Sinne schl\u00e4frig sind. \u200b<br \/>\nDrittens: Unkraut ist bekanntlich oft kaum von Weizen zu unterscheiden. Der Teufel pr\u00e4sentiert uns das B\u00f6se, den Irrtum oder die S\u00fcnde oft als offensichtliche Wahrheit oder Gutes.<\/p>\n<p>Liebe Schwestern und Br\u00fcder,<br \/>\nin diesem Gleichnis erinnert Christus uns daran, dass wir im spirituellen Sinne stets wach sein m\u00fcssen und nicht zulassen d\u00fcrfen, dass der Teufel in unserer Seele oder in unserem Herzen sein Unkraut, seine b\u00f6sen Gedanken s\u00e4t. So verhindern wir, dass wir selbst in den H\u00e4nden des B\u00f6sen &#8222;Unkraut&#8220; werden. Lasst uns nicht die Ursache des B\u00f6sen sein. Deshalb, meine Lieben, lassen wir uns nicht vom B\u00f6sen t\u00e4uschen. Lasst uns beten, die Heilige Schrift lesen, lasst uns im Namen der Herrlichkeit Jesu Christi Gutes<br \/>\ntun. Amen.<\/p>\n<p>Pfr. Vahridsch Baghdasaryan<\/p>","protected":false},"excerpt":{"rendered":"<p>Heute erinnert unsere Kirche an die Auffindung der Schatulle der  [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":6580,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[129,107],"tags":[],"class_list":["post-5740","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-baghdasaryan","category-glaubensfragen"],"_links":{"self":[{"href":"https:\/\/mainz.dakd.de\/am\/wp-json\/wp\/v2\/posts\/5740","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mainz.dakd.de\/am\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mainz.dakd.de\/am\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mainz.dakd.de\/am\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mainz.dakd.de\/am\/wp-json\/wp\/v2\/comments?post=5740"}],"version-history":[{"count":0,"href":"https:\/\/mainz.dakd.de\/am\/wp-json\/wp\/v2\/posts\/5740\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mainz.dakd.de\/am\/wp-json\/wp\/v2\/media\/6580"}],"wp:attachment":[{"href":"https:\/\/mainz.dakd.de\/am\/wp-json\/wp\/v2\/media?parent=5740"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mainz.dakd.de\/am\/wp-json\/wp\/v2\/categories?post=5740"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mainz.dakd.de\/am\/wp-json\/wp\/v2\/tags?post=5740"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}